{"id":4141,"count":1,"description":"","link":"https:\/\/www.wasobamaborninkenya.com\/blog\/tag\/attorney-general-githu-muigai-kenya\/","name":"Attorney General Githu Muigai Kenya","slug":"attorney-general-githu-muigai-kenya","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.wasobamaborninkenya.com\/blog\/tag\/attorney-general-githu-muigai-kenya\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4141\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/tag\\\/attorney-general-githu-muigai-kenya\\\/#listItem\",\"name\":\"Attorney General Githu Muigai Kenya\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/tag\\\/attorney-general-githu-muigai-kenya\\\/#listItem\",\"position\":2,\"name\":\"Attorney General Githu Muigai Kenya\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4141\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4141\\\/\",\"name\":\"Attorney General Githu Muigai Kenya | WOBIK Blog\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4141\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/#organization\",\"name\":\"WOBIK Blog\",\"description\":\"Presenting a Wide Variety of Interesting Topics Relating to the Eligibility Issues of Barack Obama and many others\",\"url\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/\",\"name\":\"Lucas Daniel Smith's blog\",\"description\":\"Presenting a Wide Variety of Interesting Topics Relating to the Eligibility Issues of Barack Obama and many others\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wasobamaborninkenya.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Attorney General Githu Muigai Kenya | WOBIK Blog","description":"","canonical_url":"https:\/\/www.wasobamaborninkenya.com\/blog\/tag\/attorney-general-githu-muigai-kenya\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/wp-json\/wp\/v2\/tags\/4141\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.wasobamaborninkenya.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.wasobamaborninkenya.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/tag\/attorney-general-githu-muigai-kenya\/#listItem","name":"Attorney General Githu Muigai Kenya"}},{"@type":"ListItem","@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/tag\/attorney-general-githu-muigai-kenya\/#listItem","position":2,"name":"Attorney General Githu Muigai Kenya","previousItem":{"@type":"ListItem","@id":"https:\/\/www.wasobamaborninkenya.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/wp-json\/wp\/v2\/tags\/4141\/#collectionpage","url":"https:\/\/www.wasobamaborninkenya.com\/blog\/wp-json\/wp\/v2\/tags\/4141\/","name":"Attorney General Githu Muigai Kenya | WOBIK Blog","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/wp-json\/wp\/v2\/tags\/4141\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/#organization","name":"WOBIK Blog","description":"Presenting a Wide Variety of Interesting Topics Relating to the Eligibility Issues of Barack Obama and many others","url":"https:\/\/www.wasobamaborninkenya.com\/blog\/"},{"@type":"WebSite","@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/#website","url":"https:\/\/www.wasobamaborninkenya.com\/blog\/","name":"Lucas Daniel Smith's blog","description":"Presenting a Wide Variety of Interesting Topics Relating to the Eligibility Issues of Barack Obama and many others","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.wasobamaborninkenya.com\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.wasobamaborninkenya.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAttorney General Githu Muigai Kenya\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.wasobamaborninkenya.com\/blog"},{"label":"Attorney General Githu Muigai Kenya","link":"https:\/\/www.wasobamaborninkenya.com\/blog\/tag\/attorney-general-githu-muigai-kenya\/"}],"_links":{"self":[{"href":"https:\/\/www.wasobamaborninkenya.com\/blog\/wp-json\/wp\/v2\/tags\/4141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wasobamaborninkenya.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.wasobamaborninkenya.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.wasobamaborninkenya.com\/blog\/wp-json\/wp\/v2\/posts?tags=4141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}